{"id":9322,"date":"2017-09-29T02:52:10","date_gmt":"2017-09-29T05:52:10","guid":{"rendered":"http:\/\/sintrapel-limeira.org.br\/?p=9322"},"modified":"2017-09-29T02:52:10","modified_gmt":"2017-09-29T05:52:10","slug":"1a-rodada-de-negociacoes-do-setor-de-papelao-ondulado","status":"publish","type":"post","link":"https:\/\/sintrapel-limeira.org.br\/index.php\/1a-rodada-de-negociacoes-do-setor-de-papelao-ondulado\/","title":{"rendered":"1\u00aa Rodada de Negocia\u00e7\u00f5es do Setor de Papel\u00e3o Ondulado"},"content":{"rendered":"<p>Foi realizada na tarde desta \u00faltima quinta-feira (28), a reuni\u00e3o das negocia\u00e7\u00f5es salariais das categorias Papel\/Celulose. O encontro aconteceu na sede do Sindicato Patronal do Papel\u00e3o &#8211; SINPESP.<\/p>\n<p>Veja as fotos:<\/p>\n<p>[ngg_images source=&#8221;galleries&#8221; container_ids=&#8221;99&#8243; display_type=&#8221;photocrati-nextgen_basic_thumbnails&#8221; override_thumbnail_settings=&#8221;0&#8243; thumbnail_width=&#8221;240&#8243; thumbnail_height=&#8221;160&#8243; thumbnail_crop=&#8221;1&#8243; images_per_page=&#8221;21&#8243; number_of_columns=&#8221;0&#8243; ajax_pagination=&#8221;0&#8243; show_all_in_lightbox=&#8221;0&#8243; use_imagebrowser_effect=&#8221;0&#8243; show_slideshow_link=&#8221;0&#8243; slideshow_link_text=&#8221;[Show slideshow]&#8221; order_by=&#8221;sortorder&#8221; order_direction=&#8221;ASC&#8221; returns=&#8221;included&#8221; maximum_entity_count=&#8221;500&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi realizada na tarde desta \u00faltima quinta-feira (28), a reuni\u00e3o das negocia\u00e7\u00f5es salariais das categorias Papel\/Celulose. O encontro aconteceu na sede do Sindicato Patronal do Papel\u00e3o &#8211; SINPESP. Veja as&hellip; <\/p>\n","protected":false},"author":1,"featured_media":9391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[206,42,39,37,5],"tags":[294,177,69,155,179,178,101,142,244,164],"class_list":["post-9322","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-campanha-salarial","category-galeria","category-home","category-noticias","category-slider","tag-artefatos-de-papel","tag-campanha-salarial","tag-celulose","tag-negociacao","tag-papel-e-celulose","tag-papel-ondulado","tag-papelao","tag-reforma","tag-reforma-trabalhista","tag-salario","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts\/9322"}],"collection":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=9322"}],"version-history":[{"count":1,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts\/9322\/revisions"}],"predecessor-version":[{"id":9392,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts\/9322\/revisions\/9392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/media\/9391"}],"wp:attachment":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=9322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=9322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=9322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}