{"id":8903,"date":"2017-09-18T18:47:28","date_gmt":"2017-09-18T21:47:28","guid":{"rendered":"http:\/\/sintrapel-limeira.org.br\/?p=8903"},"modified":"2017-09-19T01:48:17","modified_gmt":"2017-09-19T04:48:17","slug":"lancamento-da-campanha-salarial-2017","status":"publish","type":"post","link":"https:\/\/sintrapel-limeira.org.br\/index.php\/lancamento-da-campanha-salarial-2017\/","title":{"rendered":"Lan\u00e7amento da Campanha Salarial 2017"},"content":{"rendered":"<p>Durante a madrugada desta \u00faltima segunda-feira (18) foi dado \u00ednicio \u00e0 Campanha Salarial 2017. As primeiras a\u00e7\u00f5es foram em frente \u00e0 Suzano Papel e Celulose, localizada na cidade de Limeira, inteiror de S\u00e3o Paulo. Representantes dos sindicatos de todo o Estado de S\u00e3o Paulo falaram diretamente aos trabalhadores sobre a import\u00e2ncia da uni\u00e3o entre trabalhador e sindicato, sobre as conquistas alcan\u00e7adas e sobre a grande luta que ser\u00e1 a campanha salarial deste ano, em que a reforma trabalhista est\u00e1 prestes a vigorar.<\/p>\n<p>Veja algumas fotos:<\/p>\n<p>[ngg_images source=&#8221;galleries&#8221; container_ids=&#8221;96&#8243; display_type=&#8221;photocrati-nextgen_basic_thumbnails&#8221; override_thumbnail_settings=&#8221;0&#8243; thumbnail_width=&#8221;240&#8243; thumbnail_height=&#8221;160&#8243; thumbnail_crop=&#8221;1&#8243; images_per_page=&#8221;21&#8243; number_of_columns=&#8221;0&#8243; ajax_pagination=&#8221;0&#8243; show_all_in_lightbox=&#8221;0&#8243; use_imagebrowser_effect=&#8221;0&#8243; show_slideshow_link=&#8221;0&#8243; slideshow_link_text=&#8221;[Show slideshow]&#8221; order_by=&#8221;sortorder&#8221; order_direction=&#8221;ASC&#8221; returns=&#8221;included&#8221; maximum_entity_count=&#8221;500&#8243;]<\/p>\n<p><em>Fotos: Eric Paix\u00e3o<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a madrugada desta \u00faltima segunda-feira (18) foi dado \u00ednicio \u00e0 Campanha Salarial 2017. As primeiras a\u00e7\u00f5es foram em frente \u00e0 Suzano Papel e Celulose, localizada na cidade de Limeira,&hellip; <\/p>\n","protected":false},"author":1,"featured_media":9152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[206,42,39,37,5],"tags":[289,177,69,41,179,244,164,198,105],"class_list":["post-8903","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-campanha-salarial","category-galeria","category-home","category-noticias","category-slider","tag-campanha-2017","tag-campanha-salarial","tag-celulose","tag-federacao","tag-papel-e-celulose","tag-reforma-trabalhista","tag-salario","tag-sindicatos","tag-suzano","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts\/8903"}],"collection":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=8903"}],"version-history":[{"count":1,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts\/8903\/revisions"}],"predecessor-version":[{"id":9153,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/posts\/8903\/revisions\/9153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/media\/9152"}],"wp:attachment":[{"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=8903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=8903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintrapel-limeira.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=8903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}